{"id":1664,"date":"2019-08-03T08:55:05","date_gmt":"2019-08-03T06:55:05","guid":{"rendered":"http:\/\/blog.journalismus-und-mehr.com\/?p=1664"},"modified":"2021-05-22T20:09:40","modified_gmt":"2021-05-22T18:09:40","slug":"die-musenkussmaschine","status":"publish","type":"post","link":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/archives\/1664","title":{"rendered":"Die Musenkussmaschine"},"content":{"rendered":"\n<p>Die Musenkussmaschine steht bei mir im Bad. Sie beansprucht wenig Platz,\nhat aber immer ein Auge auf mich. Gott sei Dank ist die Kamera nie an. Ich mag\nnicht beobachtet werden. Aber ich k\u00f6nnte sie in Betrieb setzen. Doch dazu\nsp\u00e4ter.<\/p>\n\n\n\n<p>Die Teilnehmer*innen aus \u201ekreativ schreiben\u201c haben mir zum\nSemesterabschluss diese Maschine geschenkt, damit mir weiterhin famose\nSchreibspiele einfallen. Ich bin zun\u00e4chst erschrocken, weil sie doch ein wenig\naussieht wie ein kostbarer, altert\u00fcmlicher Fotoapparat. Allerdings ist dieser\nauf zwei R\u00f6hren aufgeschraubt. Und seitlich h\u00e4ngt ein kleiner Hut mit Feder an\neinem Haken. <\/p>\n\n\n\n<p>Alles ist etwas unf\u00f6rmig zusammengef\u00fcgt, aber die Maschine erf\u00fcllt ihren\nZweck. Sie steht im Bad, weil sie nur nach dem H\u00e4ndewaschen benutzt werden\ndarf. Nat\u00fcrlich m\u00fcssen die H\u00e4nde sorgf\u00e4ltig abgetrocknet sein. Und beim\nAbtrocknen entscheide ich dann, ob ich die Hilfe der Musenkussmaschine in\nAnspruch nehmen will. Manchmal laufen meine Ideen auch selbst\u00e4ndig weiter und\nbrauchen keine Hilfe. Der kurze Weg zum Computer reicht dann gerade aus, damit\nsich die Formulierungen in meinem Kopf festsetzen k\u00f6nnen. Sie bleiben aber\nbeweglich, k\u00f6nnen bei Bedarf noch verschoben und erg\u00e4nzt werden.<\/p>\n\n\n\n<p>Mein Ziel ist klar umrissen: Ich will in meinen Kursen gerne helfen, dass\ndie Teilnehmer*innen unterhaltsame wie packende Texte zustande bringen, so dass\nsie mit sich zufrieden sind und immer wieder Fortschritte feiern k\u00f6nnen. Ich\nsollte also Impulse aussenden und motivieren k\u00f6nnen, damit alle das Gl\u00fcck des\nSchreibens erfahren. Dazu habe ich einiges Handwerkszeug, brauche aber auch den\nKuss der Muse.<\/p>\n\n\n\n<p>Wenn dieser nicht auf Zuruf kommt, lege ich meine H\u00e4nde in die R\u00f6hren,\nschlie\u00dfe die Augen und z\u00e4hle bis elf. Dann durchl\u00e4uft mich ein Gl\u00fccksgef\u00fchl, und\ndie Arbeit am PC beginnt. Wenn dies nicht von Erfolg gekr\u00f6nt ist, nehme ich den\nkleinen Hut vom Haken und setze ihn auf meine Tastatur. N\u00fctzt das immer noch\nnichts, bleibt mir nichts anderes \u00fcbrig, als dessen kleine Feder zu nehmen und\nmir damit \u00fcber alle zehn Finger zu streichen, bis diese von selbst lostippen. <\/p>\n\n\n\n<p>Mit der Kamera k\u00f6nnte ich nun festhalten, wie ich vor dem Inspiriertsein\naussah und wie nach erfolgter Arbeit. Aber ich sagte ja schon: darauf verzichte\nich. Dazu bin ich einfach zu eitel. <\/p>\n\n\n\n<p><em><strong>\u201eDie Musenkussmischmaschine\u201c<\/strong> ist ein Buch, das ich bis jetzt noch nicht gelesen habe. Aber der Titel \u201ebleibt h\u00e4ngen\u201c und inspiriert. Das Buch von Gerd Herholz und Bettina Mosler erschien 2003 und enth\u00e4lt mehr als 100 Schreibspiele. <\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.journalismus-und-mehr.com\/wp-content\/uploads\/2019\/08\/20190718_090639-768x1024.jpg\" alt=\"\" class=\"wp-image-1662\" width=\"384\" height=\"512\" srcset=\"https:\/\/blog.journalismus-und-mehr.com\/wp-content\/uploads\/2019\/08\/20190718_090639-768x1024.jpg 768w, https:\/\/blog.journalismus-und-mehr.com\/wp-content\/uploads\/2019\/08\/20190718_090639-225x300.jpg 225w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure><\/div>\n\n\n\n<p><span style=\"color: #0000ff;\"><span style=\"color: #333399;\">Ein mitrei\u00dfender Titel, eine flotte Schreibe und viele Tipps &#8211; dieser Ratgeber kann die Lust aufs Schreiben f\u00f6rdern und \u00fcber etwaige Klippen hinweghelfen! <\/span><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><span style=\"color: #333399;\">Cornelia J\u00f6nsson. <strong>Der Sprung ins wei\u00dfe Blatt.<\/strong> Okt. 2017, 220 Seiten, Autorenhaus-Verlag, \u20ac 12,80, ISBN 978-3866711440<\/span> <\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Musenkussmaschine steht bei mir im Bad. Sie beansprucht wenig Platz, hat aber immer ein Auge auf mich. Gott sei Dank ist die Kamera nie an. Ich mag nicht beobachtet werden. Aber ich k\u00f6nnte sie in Betrieb setzen. Doch dazu sp\u00e4ter. Die Teilnehmer*innen aus \u201ekreativ schreiben\u201c haben mir zum Semesterabschluss diese Maschine geschenkt, damit mir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[8],"tags":[1102,1104,1103,1106,1105],"class_list":["post-1664","post","type-post","status-publish","format-standard","hentry","category-literatur","tag-gluecksgefuehl","tag-inspiration","tag-muse","tag-schreibratgeber-autorenhausverlag","tag-schreibspiele"],"_links":{"self":[{"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/posts\/1664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":4,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/posts\/1664\/revisions"}],"predecessor-version":[{"id":1824,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/posts\/1664\/revisions\/1824"}],"wp:attachment":[{"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/media?parent=1664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/categories?post=1664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.journalismus-und-mehr.com\/index.php\/wp-json\/wp\/v2\/tags?post=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}